{"id":991082,"date":"2025-02-12T09:14:11","date_gmt":"2025-02-12T07:14:11","guid":{"rendered":"https:\/\/www.bexel.io\/module-de-traitement-par-lots\/"},"modified":"2026-01-05T14:32:49","modified_gmt":"2026-01-05T12:32:49","slug":"module-de-traitement-par-lots","status":"publish","type":"page","link":"https:\/\/www.bexel.io\/fr\/module-de-traitement-par-lots\/","title":{"rendered":"Module de traitement par lots"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"991082\" class=\"elementor elementor-991082 elementor-989594\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c8eab3 e-flex e-con-boxed e-con e-parent\" data-id=\"2c8eab3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d18c7a1 e-con-full e-flex e-con e-child\" data-id=\"d18c7a1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a41678b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a41678b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Module de traitement par lots<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8fd719 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b8fd719\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">La gestion des inspections et certifications \u00e0 grande \u00e9chelle peut s'av\u00e9rer fastidieuse, mais gr\u00e2ce au module d'inspection par lots de Bexel, nous simplifions l'ensemble du processus. Ce module est con\u00e7u pour rationaliser les importations d'\u00e9quipements en vrac, automatiser la g\u00e9n\u00e9ration des certifications et am\u00e9liorer la pr\u00e9cision des donn\u00e9es, garantissant ainsi un flux de travail efficace et sans erreur. <\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-a98aab6 elementor-widget__width-auto elementor-align-right elementor-widget elementor-widget-button\" data-id=\"a98aab6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/calcom.bexel.io\/team\/sales\/discovery\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Parlez \u00e0 notre \u00e9quipe commerciale<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4542baa elementor-widget elementor-widget-spacer\" data-id=\"4542baa\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cce19c e-con-full e-flex e-con e-child\" data-id=\"0cce19c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-feddb96 elementor-widget elementor-widget-spacer\" data-id=\"feddb96\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb17728 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb17728\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5a58cd7\" data-id=\"5a58cd7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a814b9 elementor-widget elementor-widget-heading\" data-id=\"2a814b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Principales caract\u00e9ristiques et fonctionnalit\u00e9s<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f8dfcb1 elementor-section-height-full elementor-section-content-middle elementor-section-boxed elementor-section-height-default\" data-id=\"f8dfcb1\" data-element_type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-d050840\" data-id=\"d050840\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b904a0\" data-id=\"2b904a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5a3fc7 e-flex e-con-boxed e-con e-parent\" data-id=\"c5a3fc7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b43db4b e-con-full e-flex e-con e-child\" data-id=\"b43db4b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b12767 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4b12767\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M14 20H26C26.2652 20 26.5196 19.8946 26.7071 19.7071C26.8946 19.5196 27 19.2652 27 19C27 18.7348 26.8946 18.4804 26.7071 18.2929C26.5196 18.1054 26.2652 18 26 18H14C13.7348 18 13.4804 18.1054 13.2929 18.2929C13.1054 18.4804 13 18.7348 13 19C13 19.2652 13.1054 19.5196 13.2929 19.7071C13.4804 19.8946 13.7348 20 14 20Z\" fill=\"#00C65B\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16 5V9C16 9.79565 16.3161 10.5587 16.8787 11.1213C17.4413 11.6839 18.2044 12 19 12H23C23.2652 12 23.5196 11.8946 23.7071 11.7071C23.8946 11.5196 24 11.2652 24 11C24 10.7348 23.8946 10.4804 23.7071 10.2929C23.5196 10.1054 23.2652 10 23 10H19C18.7348 10 18.4804 9.89464 18.2929 9.70711C18.1054 9.51957 18 9.26522 18 9V5C18 4.73478 17.8946 4.48043 17.7071 4.29289C17.5196 4.10536 17.2652 4 17 4C16.7348 4 16.4804 4.10536 16.2929 4.29289C16.1054 4.48043 16 4.73478 16 5Z\" fill=\"#00C65B\"><\/path><path d=\"M13.4146 19L16.7076 15.707C16.8897 15.5184 16.9905 15.2658 16.9882 15.0036C16.986 14.7414 16.8808 14.4906 16.6954 14.3052C16.51 14.1198 16.2592 14.0146 15.997 14.0124C15.7348 14.0101 15.4822 14.1109 15.2936 14.293L11.2936 18.293C11.2006 18.3858 11.1269 18.496 11.0766 18.6173C11.0263 18.7387 11.0004 18.8687 11.0004 19C11.0004 19.1314 11.0263 19.2614 11.0766 19.3827C11.1269 19.504 11.2006 19.6143 11.2936 19.707L15.2936 23.707C15.4822 23.8892 15.7348 23.99 15.997 23.9877C16.2592 23.9854 16.51 23.8803 16.6954 23.6949C16.8808 23.5094 16.986 23.2586 16.9882 22.9964C16.9905 22.7342 16.8897 22.4816 16.7076 22.293L13.4146 19Z\" fill=\"#00C65B\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M25 15V11C25.0001 10.8687 24.9743 10.7386 24.924 10.6173C24.8738 10.4959 24.8 10.3857 24.707 10.293L17.707 3.293C17.6143 3.2 17.5041 3.12624 17.3827 3.07596C17.2614 3.02568 17.1313 2.99986 17 3H9C8.204 3 7.441 3.316 6.879 3.879C6.60023 4.15738 6.3791 4.48801 6.22827 4.85196C6.07744 5.21591 5.99987 5.60603 6 6V26C6 26.796 6.316 27.559 6.879 28.121C7.15738 28.3998 7.48801 28.6209 7.85196 28.7717C8.21591 28.9226 8.60603 29.0001 9 29H22C22.796 29 23.559 28.684 24.121 28.121C24.3998 27.8426 24.6209 27.512 24.7717 27.148C24.9226 26.7841 25.0001 26.394 25 26V23C25 22.7348 24.8946 22.4804 24.7071 22.2929C24.5196 22.1054 24.2652 22 24 22C23.7348 22 23.4804 22.1054 23.2929 22.2929C23.1054 22.4804 23 22.7348 23 23V26C23.0004 26.1314 22.9748 26.2616 22.9247 26.3832C22.8746 26.5047 22.8009 26.6151 22.708 26.708C22.6151 26.8009 22.5047 26.8746 22.3832 26.9247C22.2616 26.9748 22.1314 27.0004 22 27H9C8.86857 27.0004 8.73835 26.9748 8.61685 26.9247C8.49534 26.8746 8.38495 26.8009 8.29201 26.708C8.19907 26.6151 8.12543 26.5047 8.07531 26.3832C8.0252 26.2616 7.9996 26.1314 8 26V6C7.9996 5.86857 8.0252 5.73835 8.07531 5.61685C8.12543 5.49534 8.19907 5.38495 8.29201 5.29201C8.38495 5.19907 8.49534 5.12543 8.61685 5.07531C8.73835 5.0252 8.86857 4.9996 9 5H16.586L23 11.414V15C23 15.2652 23.1054 15.5196 23.2929 15.7071C23.4804 15.8946 23.7348 16 24 16C24.2652 16 24.5196 15.8946 24.7071 15.7071C24.8946 15.5196 25 15.2652 25 15Z\" fill=\"#00C65B\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6566d13 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"6566d13\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Importer et g\u00e9rer les inspections par lots<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4aae98c e-con-full e-flex e-con e-child\" data-id=\"4aae98c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf1ecb2 elementor-widget elementor-widget-text-editor\" data-id=\"bf1ecb2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Importation facile des donn\u00e9es<\/strong> : T\u00e9l\u00e9chargez rapidement des donn\u00e9es d&rsquo;\u00e9quipement en masse \u00e0 l&rsquo;aide de mod\u00e8les pr\u00e9d\u00e9finis.<\/li><li><strong>Deux options d&rsquo;importation<\/strong> : Choisissez comment associer les \u00e9quipements et les certificats :\u20281- Certificat unique pour tous les \u00e9quipements \u2022 Id\u00e9al pour la certification en masse.\u20282- Certificat individuel pour chaque \u00e9quipement \u2022 Garantit un suivi d\u00e9taill\u00e9 de chaque article.<\/li><li><strong>Cartographie automatis\u00e9e des \u00e9quipements<\/strong> : Comparez les donn\u00e9es t\u00e9l\u00e9charg\u00e9es avec les enregistrements du syst\u00e8me afin d&rsquo;\u00e9viter toute divergence.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f19f0a0 e-flex e-con-boxed e-con e-parent\" data-id=\"f19f0a0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-768ae47 e-con-full e-flex e-con e-child\" data-id=\"768ae47\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4979ab9 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4979ab9\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><g clip-path=\"url(#clip0_25_1926)\"><path d=\"M31.2563 7.39367C31.2563 5.6798 29.8618 4.2853 28.1479 4.2853H22.4814C21.1057 2.15755 18.7173 0.74292 16.0007 0.74292C13.2841 0.74292 10.8956 2.15755 9.51994 4.2853H3.85106C2.13669 4.2853 0.742188 5.6798 0.742188 7.39367L0.743562 22.9497C0.743562 24.6664 2.13806 26.0627 3.85244 26.0627H12.1324V30.3035H8.79906C8.5355 30.3035 8.32225 30.5167 8.32225 30.7803C8.32225 31.0439 8.5355 31.2571 8.79906 31.2571H23.2022C23.4657 31.2571 23.679 31.0439 23.679 30.7803C23.679 30.5167 23.4657 30.3035 23.2022 30.3035H19.8689V26.0627H28.1493C29.8632 26.0627 31.2577 24.6664 31.2577 22.9497L31.2563 7.39367ZM16.0006 1.69648C19.7301 1.69648 22.7645 4.73086 22.7645 8.46036C22.7645 12.1899 19.7301 15.2242 16.0006 15.2242C12.2711 15.2242 9.23675 12.1899 9.23675 8.46036C9.23675 4.73086 12.2711 1.69648 16.0006 1.69648ZM3.85106 5.23886H8.99706C8.54344 6.22079 8.28319 7.30967 8.28319 8.46042C8.28319 12.7156 11.7454 16.1779 16.0006 16.1779C20.2558 16.1779 23.7181 12.7156 23.7181 8.46042C23.7181 7.30967 23.4578 6.22086 23.0042 5.23886H28.1479C29.3361 5.23886 30.3027 6.20548 30.3027 7.39367C30.1734 18.9634 30.5916 18.929 29.9344 19.9018C29.5467 20.4744 28.8913 20.8516 28.1493 20.8516H3.85244C2.66419 20.8516 1.69713 19.8845 1.69713 18.6963L1.69575 7.39367C1.69575 6.20542 2.66281 5.23886 3.85106 5.23886ZM18.9154 30.3035H13.0859V26.0627H18.9154V30.3035ZM30.3041 22.9497C30.3041 24.1402 29.3375 25.1092 28.1493 25.1092C22.525 25.1087 9.44956 25.1091 3.8525 25.1092C2.66425 25.1092 1.69719 24.1402 1.69719 22.9497V20.935C2.2565 21.4737 3.015 21.807 3.85106 21.807H28.1479C28.9561 21.807 29.7307 21.4876 30.3041 20.935V22.9497Z\" fill=\"#00C65B\" stroke=\"#00C65B\" stroke-width=\"0.8\"><\/path><path d=\"M16.0002 8.83945C16.0629 8.8395 16.1249 8.82719 16.1828 8.80324C16.2406 8.77929 16.2932 8.74417 16.3375 8.69989C16.3818 8.65561 16.4169 8.60303 16.4409 8.54516C16.4648 8.48729 16.4771 8.42527 16.4771 8.36264V5.9657C16.4771 5.70214 16.2638 5.48889 16.0002 5.48889C15.7367 5.48889 15.5234 5.70214 15.5234 5.9657V8.36264C15.5234 8.42526 15.5357 8.48728 15.5597 8.54514C15.5836 8.603 15.6188 8.65557 15.663 8.69985C15.7073 8.74414 15.7599 8.77926 15.8178 8.80321C15.8756 8.82716 15.9376 8.83948 16.0002 8.83945ZM16.0002 11.4315C16.0629 11.4315 16.1249 11.4192 16.1828 11.3952C16.2406 11.3713 16.2932 11.3362 16.3375 11.2919C16.3818 11.2476 16.4169 11.195 16.4409 11.1372C16.4648 11.0793 16.4771 11.0173 16.4771 10.9546V10.6953C16.4771 10.4318 16.2638 10.2185 16.0002 10.2185C15.7367 10.2185 15.5234 10.4318 15.5234 10.6953V10.9546C15.5234 11.0173 15.5357 11.0793 15.5597 11.1371C15.5836 11.195 15.6188 11.2476 15.663 11.2919C15.7073 11.3361 15.7599 11.3713 15.8178 11.3952C15.8756 11.4192 15.9376 11.4315 16.0002 11.4315Z\" fill=\"#00C65B\" stroke=\"#00C65B\" stroke-width=\"0.8\"><\/path><\/g><defs><clipPath id=\"clip0_25_1926\"><rect width=\"32\" height=\"32\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49e420e elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"49e420e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9tection intelligente des erreurs et suivi des journaux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d4d72b e-con-full e-flex e-con e-child\" data-id=\"5d4d72b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-055d7a2 elementor-widget elementor-widget-text-editor\" data-id=\"055d7a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>V\u00e9rification des erreurs en temps r\u00e9el<\/strong> : D\u00e9tecte automatiquement les incoh\u00e9rences dans les donn\u00e9es import\u00e9es.<\/li><li><strong>Journaux d&rsquo;erreurs t\u00e9l\u00e9chargeables<\/strong> : identifiez et r\u00e9solvez rapidement les incoh\u00e9rences dans les donn\u00e9es.<\/li><li><strong>Processus de correction simplifi\u00e9<\/strong> : corrigez facilement les erreurs et t\u00e9l\u00e9chargez \u00e0 nouveau les donn\u00e9es corrig\u00e9es.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4305343 e-flex e-con-boxed e-con e-parent\" data-id=\"4305343\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ff48f37 e-con-full e-flex e-con e-child\" data-id=\"ff48f37\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f94d9e8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f94d9e8\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path d=\"M24.75 13.3147V2.17147C24.75 0.974083 23.7759 0 22.5785 0H4.92245C3.72506 0 2.75098 0.974083 2.75098 2.17147V25.3273C2.75098 26.5247 3.72506 27.4988 4.92245 27.4988H18.2503V30.9987C18.2503 31.7634 19.0784 32.2485 19.7464 31.8669L22.7501 30.1505C26.0677 32.0462 25.8943 31.9986 26.25 31.9986C26.8022 31.9986 27.2499 31.5503 27.2499 30.9987V24.1848C30.809 20.7656 29.3993 14.8217 24.75 13.3147ZM4.92245 25.4989C4.87696 25.4989 4.83335 25.4808 4.80119 25.4486C4.76903 25.4164 4.75094 25.3728 4.75089 25.3273V2.17147C4.75094 2.12599 4.76903 2.08238 4.80119 2.05022C4.83335 2.01805 4.87696 1.99996 4.92245 1.99991H22.5786C22.624 1.99996 22.6677 2.01805 22.6998 2.05022C22.732 2.08238 22.7501 2.12599 22.7501 2.17147V12.9994C19.1661 12.9994 16.2504 15.9152 16.2504 19.4992C16.2504 21.3383 17.0184 23.0013 18.2503 24.1848V25.4989H4.92245ZM25.25 29.2756L23.2462 28.1305C23.0951 28.0442 22.9241 27.9988 22.7501 27.9988C22.5761 27.9988 22.405 28.0442 22.254 28.1305L20.2502 29.2756V25.4986C21.8447 26.1655 23.6533 26.1664 25.2499 25.4986L25.25 29.2756ZM22.7501 23.999C20.2689 23.999 18.2503 21.9804 18.2503 19.4992C18.2503 17.018 20.2689 14.9994 22.7501 14.9994C25.2313 14.9994 27.2499 17.018 27.2499 19.4992C27.2499 21.9804 25.2313 23.999 22.7501 23.999Z\" fill=\"#00C65B\"><\/path><path d=\"M22.2494 22.0616C21.8588 22.0616 21.8091 21.9692 20.1958 20.8936C19.7362 20.5873 19.612 19.9664 19.9184 19.5069C20.2248 19.0474 20.8456 18.9233 21.3051 19.2296L21.9731 19.6749L23.4183 17.507C23.7246 17.0475 24.3456 16.9234 24.805 17.2297C25.2645 17.536 25.3887 18.1569 25.0824 18.6164L23.0824 21.6162C22.8896 21.9053 22.5725 22.0616 22.2494 22.0616ZM17.2506 6.99967H8.75093C8.19871 6.99967 7.75098 6.55194 7.75098 5.99971C7.75098 5.44749 8.19871 4.99976 8.75093 4.99976H17.2506C17.8029 4.99976 18.2505 5.44749 18.2505 5.99971C18.2505 6.55194 17.8028 6.99967 17.2506 6.99967ZM17.2506 10.9995H8.75093C8.19871 10.9995 7.75098 10.5518 7.75098 9.99954C7.75098 9.44731 8.19871 8.99958 8.75093 8.99958H17.2506C17.8029 8.99958 18.2505 9.44731 18.2505 9.99954C18.2505 10.5518 17.8028 10.9995 17.2506 10.9995ZM13.7507 14.9993H8.75093C8.19871 14.9993 7.75098 14.5516 7.75098 13.9994C7.75098 13.4471 8.19871 12.9994 8.75093 12.9994H13.7507C14.3029 12.9994 14.7507 13.4471 14.7507 13.9994C14.7507 14.5516 14.3029 14.9993 13.7507 14.9993Z\" fill=\"#00C65B\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d261b5a elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"d261b5a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">G\u00e9n\u00e9ration automatis\u00e9e de certificats<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65d9f49 e-con-full e-flex e-con e-child\" data-id=\"65d9f49\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35ba090 elementor-widget elementor-widget-text-editor\" data-id=\"35ba090\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Certification par lots<\/strong> : G\u00e9n\u00e9rez automatiquement des certificats pour les \u00e9quipements import\u00e9s.<\/li><li><strong>Gestion flexible des certificats <\/strong>: affichez, modifiez, imprimez et t\u00e9l\u00e9chargez des certificats individuels ou par lots.<br>Transparence<\/li><li><strong>Int\u00e9gration avec les certificats d&rsquo;inspection<\/strong> : Modifiez et g\u00e9rez les certificats dans le module Certificats d&rsquo;inspection.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b16243 e-flex e-con-boxed e-con e-parent\" data-id=\"4b16243\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f153691 e-con-full e-flex e-con e-child\" data-id=\"f153691\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b44a7a1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b44a7a1\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"32\" height=\"32\" viewBox=\"0 0 32 32\" fill=\"none\"><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M16 20H28C28.2652 20 28.5196 19.8946 28.7071 19.7071C28.8946 19.5196 29 19.2652 29 19C29 18.7348 28.8946 18.4804 28.7071 18.2929C28.5196 18.1054 28.2652 18 28 18H16C15.7348 18 15.4804 18.1054 15.2929 18.2929C15.1054 18.4804 15 18.7348 15 19C15 19.2652 15.1054 19.5196 15.2929 19.7071C15.4804 19.8946 15.7348 20 16 20Z\" fill=\"#00C65B\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M24.293 15.707L27.586 19L24.293 22.293C24.1108 22.4816 24.01 22.7342 24.0123 22.9964C24.0146 23.2586 24.1198 23.5094 24.3052 23.6948C24.4906 23.8802 24.7414 23.9854 25.0036 23.9877C25.2658 23.99 25.5184 23.8892 25.707 23.707L29.707 19.707C29.7999 19.6142 29.8737 19.504 29.924 19.3827C29.9743 19.2614 30.0002 19.1313 30.0002 19C30.0002 18.8687 29.9743 18.7386 29.924 18.6173C29.8737 18.496 29.7999 18.3858 29.707 18.293L25.707 14.293C25.5184 14.1108 25.2658 14.01 25.0036 14.0123C24.7414 14.0146 24.4906 14.1198 24.3052 14.3052C24.1198 14.4906 24.0146 14.7414 24.0123 15.0036C24.01 15.2658 24.1108 15.5184 24.293 15.707ZM14 5V9C14 9.79565 14.3161 10.5587 14.8787 11.1213C15.4413 11.6839 16.2044 12 17 12H21C21.2652 12 21.5196 11.8946 21.7071 11.7071C21.8946 11.5196 22 11.2652 22 11C22 10.7348 21.8946 10.4804 21.7071 10.2929C21.5196 10.1054 21.2652 10 21 10H17C16.7348 10 16.4804 9.89464 16.2929 9.70711C16.1054 9.51957 16 9.26522 16 9V5C16 4.73478 15.8946 4.48043 15.7071 4.29289C15.5196 4.10536 15.2652 4 15 4C14.7348 4 14.4804 4.10536 14.2929 4.29289C14.1054 4.48043 14 4.73478 14 5Z\" fill=\"#00C65B\"><\/path><path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23 15V11C23.0001 10.8687 22.9743 10.7386 22.924 10.6173C22.8738 10.4959 22.8 10.3857 22.707 10.293L15.707 3.293C15.6143 3.2 15.5041 3.12624 15.3827 3.07596C15.2614 3.02568 15.1313 2.99986 15 3H7C6.204 3 5.441 3.316 4.879 3.879C4.60023 4.15738 4.3791 4.48801 4.22827 4.85196C4.07744 5.21591 3.99987 5.60603 4 6V26C4 26.796 4.316 27.559 4.879 28.121C5.15738 28.3998 5.48801 28.6209 5.85196 28.7717C6.21591 28.9226 6.60603 29.0001 7 29H20C20.796 29 21.559 28.684 22.121 28.121C22.3998 27.8426 22.6209 27.512 22.7717 27.148C22.9226 26.7841 23.0001 26.394 23 26V23C23 22.7348 22.8946 22.4804 22.7071 22.2929C22.5196 22.1054 22.2652 22 22 22C21.7348 22 21.4804 22.1054 21.2929 22.2929C21.1054 22.4804 21 22.7348 21 23V26C21.0004 26.1314 20.9748 26.2616 20.9247 26.3832C20.8746 26.5047 20.8009 26.6151 20.708 26.708C20.6151 26.8009 20.5047 26.8746 20.3832 26.9247C20.2616 26.9748 20.1314 27.0004 20 27H7C6.86857 27.0004 6.73835 26.9748 6.61685 26.9247C6.49534 26.8746 6.38495 26.8009 6.29201 26.708C6.19907 26.6151 6.12543 26.5047 6.07531 26.3832C6.0252 26.2616 5.9996 26.1314 6 26V6C5.9996 5.86857 6.0252 5.73835 6.07531 5.61685C6.12543 5.49534 6.19907 5.38495 6.29201 5.29201C6.38495 5.19907 6.49534 5.12543 6.61685 5.07531C6.73835 5.0252 6.86857 4.9996 7 5H14.586L21 11.414V15C21 15.2652 21.1054 15.5196 21.2929 15.7071C21.4804 15.8946 21.7348 16 22 16C22.2652 16 22.5196 15.8946 22.7071 15.7071C22.8946 15.5196 23 15.2652 23 15Z\" fill=\"#00C65B\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d9a5073 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"d9a5073\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suivi et exportation des lots<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-210e0e9 e-con-full e-flex e-con e-child\" data-id=\"210e0e9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b4d8b89 elementor-widget elementor-widget-text-editor\" data-id=\"b4d8b89\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Afficher tous les lots import\u00e9s<\/strong> : Suivez les \u00e9quipements et leurs certificats associ\u00e9s en un seul endroit.<\/li><li><strong>Exporter les donn\u00e9es et certificats relatifs aux \u00e9quipements<\/strong> : G\u00e9n\u00e9rez des rapports et exportez les d\u00e9tails dans plusieurs formats pour faciliter le partage.<\/li><li><strong>Modifier et g\u00e9rer les certificats<\/strong> : Modifiez les certificats m\u00eame apr\u00e8s leur importation group\u00e9e afin d&rsquo;en garantir l&rsquo;exactitude.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12efdd5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12efdd5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-eae34fd\" data-id=\"eae34fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a9b5f0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"7a9b5f0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi choisir le module d'inspection des installations de traitement par lots de Bexel ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca76f0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca76f0b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15008d4\" data-id=\"15008d4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63d5817 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"63d5817\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_25_1741)\"><path d=\"M18.3947 37.5781C16.7231 37.576 15.094 37.0507 13.7361 36.0757C12.3783 35.1008 11.3597 33.7251 10.8235 32.1418C10.2872 30.5586 10.2601 28.8471 10.7459 27.2477C11.2318 25.6482 12.2063 24.241 13.5326 23.2235C14.8589 22.206 16.4705 21.6294 18.1412 21.5744C19.812 21.5194 21.458 21.989 22.8483 22.9171C24.2386 23.8452 25.3034 25.1853 25.8934 26.7494C26.4833 28.3134 26.5688 30.023 26.1377 31.6381C26.0919 31.8329 26.0075 32.0167 25.8896 32.1785C25.7716 32.3402 25.6225 32.4767 25.451 32.58C25.2794 32.6832 25.089 32.7511 24.8908 32.7795C24.6926 32.808 24.4908 32.7965 24.2971 32.7457C24.1035 32.695 23.9219 32.606 23.7632 32.4839C23.6045 32.3619 23.4718 32.2093 23.373 32.0352C23.2742 31.8611 23.2112 31.669 23.1878 31.4702C23.1644 31.2714 23.181 31.0699 23.2367 30.8776C23.3509 30.4494 23.4089 30.0082 23.4092 29.5651C23.4075 28.415 23.0099 27.3005 22.2832 26.4092C21.5564 25.5178 20.5449 24.9039 19.4187 24.6707C18.2925 24.4375 17.1204 24.5992 16.0994 25.1287C15.0784 25.6581 14.2709 26.523 13.8127 27.5778C13.3544 28.6327 13.2734 29.8132 13.5833 30.9207C13.8931 32.0283 14.5749 32.9954 15.514 33.6593C16.453 34.3233 17.5921 34.6436 18.7396 34.5664C19.8871 34.4893 20.973 34.0193 21.8147 33.2356C21.9578 33.0963 22.1274 32.987 22.3133 32.9142C22.4992 32.8413 22.6978 32.8063 22.8975 32.8112C23.0971 32.8161 23.2938 32.8608 23.4759 32.9428C23.6581 33.0247 23.822 33.1421 23.9581 33.2883C24.0943 33.4344 24.1998 33.6062 24.2687 33.7937C24.3375 33.9811 24.3682 34.1805 24.359 34.38C24.3498 34.5795 24.3009 34.7751 24.215 34.9554C24.1292 35.1357 24.0082 35.2971 23.8592 35.4301C22.3762 36.8135 20.4228 37.5813 18.3947 37.5781Z\" fill=\"#00C65B\"><\/path><path d=\"M31.4218 48C29.3213 48 27.2681 47.3772 25.5216 46.2102C23.7752 45.0433 22.414 43.3847 21.6102 41.4441C20.8064 39.5036 20.596 37.3682 21.0058 35.3082C21.4156 33.2481 22.4271 31.3558 23.9123 29.8705C25.3975 28.3853 27.2898 27.3738 29.3499 26.9641C31.41 26.5543 33.5453 26.7646 35.4859 27.5684C37.4264 28.3722 39.085 29.7334 40.252 31.4799C41.4189 33.2263 42.0418 35.2796 42.0418 37.38C42.039 40.1958 40.9192 42.8954 38.9282 44.8864C36.9371 46.8775 34.2375 47.9972 31.4218 48ZM31.4218 29.7615C29.9147 29.7615 28.4414 30.2084 27.1883 31.0457C25.9352 31.883 24.9585 33.0731 24.3818 34.4655C23.8051 35.8578 23.6542 37.39 23.9482 38.8681C24.2422 40.3462 24.9679 41.704 26.0336 42.7697C27.0993 43.8353 28.457 44.5611 29.9352 44.8551C31.4133 45.1491 32.9454 44.9982 34.3378 44.4215C35.7302 43.8447 36.9203 42.8681 37.7576 41.615C38.5949 40.3619 39.0418 38.8886 39.0418 37.3815C39.0394 35.3613 38.2358 33.4245 36.8073 31.996C35.3788 30.5675 33.442 29.7639 31.4218 29.7615Z\" fill=\"#00C65B\"><\/path><path d=\"M19.3845 47.9999H17.4045C16.7998 47.9994 16.2117 47.8025 15.7286 47.4389C15.2455 47.0754 14.8934 46.5648 14.7255 45.9839L13.938 43.3784C13.1947 43.1421 12.4722 42.8445 11.778 42.4889L9.35697 43.7849C8.82818 44.0722 8.22052 44.1804 7.62505 44.0934C7.02958 44.0063 6.47836 43.7286 6.05397 43.3019L4.65897 41.9084C4.23129 41.483 3.95326 40.9302 3.8667 40.3332C3.78014 39.7362 3.88972 39.1273 4.17897 38.5979L5.46897 36.1829C5.114 35.4886 4.81699 34.7661 4.58097 34.0229L1.95147 33.2279C1.37584 33.0563 0.870988 32.7035 0.512064 32.2219C0.153139 31.7402 -0.0406727 31.1556 -0.0405273 30.5549V28.5749C-0.0398385 27.9708 0.156509 27.3831 0.519122 26.8999C0.881734 26.4167 1.3911 26.0639 1.97097 25.8944L4.58097 25.1084C4.81682 24.3651 5.11384 23.6427 5.46897 22.9484L4.17447 20.5274C3.89234 19.9971 3.78689 19.3906 3.8735 18.7962C3.96011 18.2018 4.23424 17.6506 4.65597 17.2229L6.05247 15.8279C6.47723 15.4002 7.02939 15.1221 7.62587 15.0352C8.22235 14.9484 8.8309 15.0576 9.35997 15.3464L11.778 16.6409C12.4719 16.2847 13.1944 15.9871 13.938 15.7514L14.733 13.1204C14.9038 12.5449 15.256 12.04 15.7372 11.681C16.2183 11.322 16.8026 11.1282 17.403 11.1284H19.383C19.9874 11.129 20.5753 11.3254 21.0586 11.6884C21.5419 12.0513 21.8945 12.5611 22.0635 13.1414L22.851 15.7514C23.5945 15.9871 24.3171 16.2847 25.011 16.6409L27.4305 15.3464C27.9596 15.0584 28.5679 14.9498 29.164 15.0369C29.7601 15.1239 30.3119 15.4021 30.7365 15.8294L32.13 17.2244C32.5525 17.6519 32.8274 18.2032 32.9146 18.7979C33.0017 19.3927 32.8966 19.9997 32.6145 20.5304L31.32 22.9499C31.6765 23.6439 31.9745 24.3664 32.211 25.1099L34.8405 25.9019C35.416 26.0737 35.9207 26.4266 36.2796 26.9082C36.6385 27.3898 36.8324 27.9743 36.8325 28.5749V29.1479C36.8325 29.5457 36.6744 29.9273 36.3931 30.2086C36.1118 30.4899 35.7303 30.6479 35.3325 30.6479C34.9347 30.6479 34.5531 30.4899 34.2718 30.2086C33.9905 29.9273 33.8325 29.5457 33.8325 29.1479V28.7309L30.5595 27.7439C30.3116 27.6689 30.0874 27.5309 29.9086 27.3435C29.7299 27.1561 29.6027 26.9256 29.5395 26.6744C29.2792 25.6381 28.8694 24.6452 28.323 23.7269C28.1907 23.5049 28.118 23.2525 28.112 22.9942C28.1059 22.7359 28.1667 22.4803 28.2885 22.2524L29.904 19.2374L28.722 18.0569L25.707 19.6709C25.4791 19.7927 25.2237 19.8537 24.9654 19.8479C24.7071 19.8422 24.4546 19.7698 24.2325 19.6379C23.3142 19.092 22.3212 18.6827 21.285 18.4229C21.0341 18.3595 20.8039 18.2322 20.6167 18.0535C20.4296 17.8747 20.2919 17.6506 20.217 17.4029L19.23 14.1299H17.562L16.575 17.4014C16.5003 17.6494 16.3627 17.8738 16.1755 18.0528C15.9883 18.2318 15.758 18.3593 15.507 18.4229C14.4707 18.6826 13.4778 19.0919 12.5595 19.6379C12.3373 19.7696 12.085 19.842 11.8267 19.848C11.5685 19.8541 11.3131 19.7936 11.085 19.6724L8.06847 18.0569L6.88797 19.2374L8.50197 22.2524C8.62372 22.4803 8.68451 22.7359 8.67847 22.9942C8.67242 23.2525 8.59974 23.5049 8.46747 23.7269C7.92278 24.6457 7.51404 25.6385 7.25397 26.6744C7.19062 26.9255 7.0634 27.156 6.88467 27.3434C6.70594 27.5308 6.48179 27.6687 6.23397 27.7439L2.96097 28.7309V30.3989L6.23247 31.3844C6.48063 31.4592 6.70517 31.5971 6.88419 31.7845C7.06322 31.972 7.19062 32.2026 7.25397 32.4539C7.51362 33.4902 7.92292 34.4832 8.46897 35.4014C8.60101 35.6235 8.67343 35.876 8.67921 36.1343C8.68499 36.3927 8.62394 36.6481 8.50197 36.8759L6.88797 39.8924L8.06847 41.0714L11.0835 39.4589C11.3115 39.3367 11.5672 39.2755 11.8258 39.2813C12.0844 39.287 12.3372 39.3596 12.5595 39.4919C13.4778 40.0378 14.4707 40.4471 15.507 40.7069C15.7579 40.7704 15.9881 40.8976 16.1752 41.0764C16.3623 41.2551 16.5001 41.4792 16.575 41.7269L17.5605 44.9999H19.2285L20.2155 41.7284C20.2906 41.4801 20.4287 41.2556 20.6164 41.0765C20.8041 40.8975 21.0349 40.7702 21.2865 40.7069C21.7838 40.585 22.2703 40.4229 22.7415 40.2224C23.1073 40.0659 23.5203 40.0611 23.8896 40.209C24.259 40.357 24.5544 40.6456 24.711 41.0114C24.8675 41.3772 24.8723 41.7902 24.7244 42.1596C24.5764 42.5289 24.2878 42.8244 23.922 42.9809C23.574 43.1294 23.22 43.2614 22.8525 43.3799L22.0575 46.0079C21.8857 46.5834 21.5328 47.0881 21.0512 47.447C20.5696 47.8059 19.9851 47.9998 19.3845 47.9999Z\" fill=\"#00C65B\"><\/path><path d=\"M33.2639 40.7235C33.0669 40.7237 32.8718 40.685 32.6898 40.6095C32.5078 40.5341 32.3425 40.4235 32.2034 40.284L30.3614 38.442C30.08 38.1607 29.922 37.7793 29.9219 37.3815V33.4725C29.9219 33.0747 30.0799 32.6931 30.3612 32.4118C30.6425 32.1305 31.0241 31.9725 31.4219 31.9725C31.8197 31.9725 32.2012 32.1305 32.4825 32.4118C32.7638 32.6931 32.9219 33.0747 32.9219 33.4725V36.7605L34.3244 38.163C34.5341 38.3728 34.6769 38.64 34.7348 38.9309C34.7926 39.2219 34.7629 39.5234 34.6494 39.7975C34.5359 40.0715 34.3437 40.3058 34.0971 40.4706C33.8504 40.6354 33.5605 40.7234 33.2639 40.7235ZM40.4999 18H37.4999C36.7045 17.9992 35.9419 17.6829 35.3794 17.1204C34.817 16.558 34.5007 15.7954 34.4999 15V10.5H31.4999C31.2022 10.4999 30.9112 10.4113 30.664 10.2453C30.4168 10.0794 30.2246 9.84362 30.1119 9.56808C29.9991 9.29254 29.9709 8.98968 30.0308 8.69805C30.0907 8.40642 30.2361 8.13923 30.4484 7.93048L37.9454 0.536975C38.2262 0.25942 38.6051 0.10376 38.9999 0.10376C39.3947 0.10376 39.7736 0.25942 40.0544 0.536975L47.5514 7.93198C47.7631 8.14081 47.908 8.40788 47.9676 8.69925C48.0273 8.99062 47.9989 9.29314 47.8862 9.56837C47.7735 9.8436 47.5816 10.0791 47.3347 10.245C47.0879 10.4109 46.7973 10.4996 46.4999 10.5H43.4999V15C43.4991 15.7954 43.1828 16.558 42.6203 17.1204C42.0579 17.6829 41.2953 17.9992 40.4999 18ZM35.1629 7.49998H35.9999C36.3977 7.49998 36.7792 7.65801 37.0605 7.93932C37.3418 8.22062 37.4999 8.60215 37.4999 8.99998V15H40.4999V8.99998C40.4999 8.60215 40.6579 8.22062 40.9392 7.93932C41.2205 7.65801 41.602 7.49998 41.9999 7.49998H42.8369L38.9999 3.71398L35.1629 7.49998Z\" fill=\"#00C65B\"><\/path><\/g><defs><clipPath id=\"clip0_25_1741\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c793ed elementor-widget elementor-widget-heading\" data-id=\"1c793ed\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Optimiser l'efficacit\u00e9<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52c0625 elementor-widget elementor-widget-text-editor\" data-id=\"52c0625\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Automatisez les importations par lots et la g\u00e9n\u00e9ration de certificats, r\u00e9duisant ainsi le travail manuel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a04eadd\" data-id=\"a04eadd\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a446d7 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4a446d7\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_24_310)\"><mask id=\"mask0_24_310\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"48\" height=\"48\"><path d=\"M0 0.000141144H47.9999V48H0V0.000141144Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask0_24_310)\"><path d=\"M23.9999 1.87513L5.625 9.5042V18.7784C5.625 30.7806 12.8877 41.5894 23.9999 46.125C35.1121 41.5894 42.3749 30.7806 42.3749 18.7784V9.5042L23.9999 1.87513Z\" stroke=\"#00C65B\" stroke-width=\"3.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M16.6875 22.51L21.9275 27.75L31.3125 18.3652\" stroke=\"#00C65B\" stroke-width=\"3.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><\/g><defs><clipPath id=\"clip0_24_310\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5734db7 elementor-widget elementor-widget-heading\" data-id=\"5734db7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Am\u00e9liorer la pr\u00e9cision<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9af9bf0 elementor-widget elementor-widget-text-editor\" data-id=\"9af9bf0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c9liminez les erreurs gr\u00e2ce \u00e0 une validation intelligente des donn\u00e9es et \u00e0 une d\u00e9tection des erreurs en temps r\u00e9el.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-79fbb16 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79fbb16\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-347fc3a\" data-id=\"347fc3a\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-823ba19 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"823ba19\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><path d=\"M26.1839 10.6446C26.1839 10.1571 25.9902 9.68954 25.6455 9.3448C25.3007 9.00007 24.8332 8.8064 24.3457 8.8064C23.8581 8.8064 23.3906 9.00007 23.0458 9.3448C22.7011 9.68954 22.5074 10.1571 22.5074 10.6446V20.7329L16.5932 25.1691C16.4001 25.314 16.2374 25.4954 16.1144 25.7032C15.9914 25.9109 15.9105 26.1408 15.8764 26.3798C15.8422 26.6187 15.8555 26.8621 15.9154 27.0959C15.9753 27.3298 16.0807 27.5496 16.2256 27.7427C16.3704 27.9358 16.5519 28.0985 16.7596 28.2215C16.9673 28.3445 17.1972 28.4253 17.4362 28.4595C17.6752 28.4936 17.9185 28.4804 18.1524 28.4205C18.3862 28.3605 18.606 28.2552 18.7991 28.1103L25.4486 23.1226C25.6769 22.9513 25.8622 22.7293 25.9898 22.4741C26.1174 22.2188 26.1839 21.9374 26.1839 21.652V10.6446Z\" fill=\"#00C65B\"><\/path><path d=\"M21.1397 43.1569C21.6912 43.2206 22.2598 43.2304 22.8235 43.2549C22.1913 42.068 21.7261 40.7995 21.4412 39.4853C17.089 38.9507 13.0829 36.8419 10.1788 33.5566C7.27457 30.2714 5.6731 26.0368 5.67648 21.652C5.67648 11.7402 13.7402 3.67647 23.652 3.67647C33.5613 3.67647 41.625 11.7402 41.625 21.652C41.625 22.049 41.5907 22.4363 41.5637 22.8284C42.8186 23.3676 43.9804 24.0735 45.027 24.9191C45.201 23.8386 45.2928 22.7464 45.3015 21.652C45.3015 9.71568 35.5882 0 23.652 0C11.7157 0 2.00001 9.71323 2.00001 21.652C1.99592 26.9604 3.94391 32.0851 7.47318 36.0505C11.0024 40.0159 15.8666 42.5452 21.1397 43.1569Z\" fill=\"#00C65B\"><\/path><path d=\"M35.9068 24.7156C29.4852 24.7156 24.2646 29.9362 24.2646 36.3577C24.2646 42.7793 29.4852 47.9999 35.9068 47.9999C42.3284 47.9999 47.549 42.7768 47.549 36.3577C47.549 29.9386 42.3259 24.7156 35.9068 24.7156ZM35.9068 44.3234C31.5146 44.3234 27.9411 40.7499 27.9411 36.3577C27.9411 31.9656 31.5146 28.392 35.9068 28.392C40.299 28.392 43.8725 31.9656 43.8725 36.3577C43.8725 40.7499 40.299 44.3234 35.9068 44.3234Z\" fill=\"#00C65B\"><\/path><path d=\"M37.5072 32.9217L34.9999 35.4315L34.1003 34.532C33.9321 34.3514 33.7291 34.2066 33.5036 34.1061C33.2781 34.0056 33.0347 33.9516 32.7879 33.9472C32.5411 33.9429 32.2959 33.9883 32.067 34.0807C31.8381 34.1732 31.6302 34.3108 31.4556 34.4854C31.2811 34.6599 31.1435 34.8678 31.051 35.0967C30.9586 35.3256 30.9132 35.5708 30.9175 35.8176C30.9219 36.0644 30.9759 36.3079 31.0764 36.5333C31.1768 36.7588 31.3217 36.9618 31.5023 37.1301L33.7008 39.331C33.8712 39.5021 34.0736 39.6378 34.2965 39.7304C34.5195 39.823 34.7585 39.8707 34.9999 39.8707C35.2412 39.8707 35.4803 39.823 35.7032 39.7304C35.9261 39.6378 36.1285 39.5021 36.2989 39.331L40.1077 35.5222C40.2883 35.3539 40.4332 35.151 40.5336 34.9255C40.6341 34.7 40.6881 34.4566 40.6925 34.2098C40.6968 33.963 40.6514 33.7178 40.559 33.4889C40.4665 33.26 40.3289 33.0521 40.1544 32.8775C39.9798 32.703 39.7719 32.5654 39.543 32.4729C39.3141 32.3804 39.0689 32.335 38.8221 32.3394C38.5753 32.3438 38.3319 32.3978 38.1064 32.4982C37.8809 32.5987 37.6779 32.7436 37.5097 32.9242L37.5072 32.9217Z\" fill=\"#00C65B\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4e8480 elementor-widget elementor-widget-heading\" data-id=\"b4e8480\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Gagnez du temps et \u00e9conomisez vos efforts<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5533c8c elementor-widget elementor-widget-text-editor\" data-id=\"5533c8c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Simplifiez les inspections et certifications en masse en quelques clics seulement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a28bcc8\" data-id=\"a28bcc8\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-085c6df elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"085c6df\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><path d=\"M19.0678 33.9297C25.0989 33.9297 29.9881 29.0416 29.9881 23.0117C29.9881 16.9819 25.0989 12.0938 19.0678 12.0938C13.0366 12.0938 8.14746 16.9819 8.14746 23.0117C8.14746 29.0416 13.0366 33.9297 19.0678 33.9297Z\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M26.7898 30.7319L30.0157 33.9573M39.2638 39.4614L40.4952 40.6926C40.9596 41.1568 40.9596 41.9097 40.4952 42.3738L38.4338 44.4348C37.9696 44.8989 37.217 44.8989 36.7529 44.4348L28.9853 36.6689C28.5209 36.2046 28.5209 35.4518 28.9853 34.9876L31.0467 32.9266C31.5109 32.4625 32.2635 32.4625 32.7276 32.9266L39.2624 39.4614\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M5.13875 11.6281C6.96945 11.6281 8.45352 10.1444 8.45352 8.31406C8.45352 6.48375 6.96945 5 5.13875 5C3.30805 5 1.82397 6.48375 1.82397 8.31406C1.82397 10.1444 3.30805 11.6281 5.13875 11.6281Z\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M29.2017 11.6281C31.0324 11.6281 32.5165 10.1444 32.5165 8.31406C32.5165 6.48375 31.0324 5 29.2017 5C27.371 5 25.887 6.48375 25.887 8.31406C25.887 10.1444 27.371 11.6281 29.2017 11.6281Z\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M19.0418 24.0058C20.8725 24.0058 22.3566 22.522 22.3566 20.6917C22.3566 18.8614 20.8725 17.3777 19.0418 17.3777C17.2111 17.3777 15.7271 18.8614 15.7271 20.6917C15.7271 22.522 17.2111 24.0058 19.0418 24.0058Z\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M43.1043 24.0058C44.935 24.0058 46.4191 22.522 46.4191 20.6917C46.4191 18.8614 44.935 17.3777 43.1043 17.3777C41.2736 17.3777 39.7896 18.8614 39.7896 20.6917C39.7896 22.522 41.2736 24.0058 43.1043 24.0058Z\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M12.1537 14.56L7.61426 10.5186M16.5665 18.4875L14.2013 16.3815M40.6293 18.4876L31.6768 10.5182M40.6293 18.4876L40.5 18.1303M40.6293 18.4876L40 19M23.0459 15.8135L21.1445 18.1303M27.0989 10.8757L24.7785 13.7031M42.1833 5V5.59158M42.1833 8.86571V9.45729M44.412 7.2286H43.8203M40.5462 7.2286H39.9546\" stroke=\"#00C65B\" stroke-width=\"2.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-169c937 elementor-widget elementor-widget-heading\" data-id=\"169c937\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Am\u00e9liorer la gestion des donn\u00e9es<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-193dae0 elementor-widget elementor-widget-text-editor\" data-id=\"193dae0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centralisez tous les enregistrements li\u00e9s aux lots gr\u00e2ce \u00e0 des fonctions avanc\u00e9es de suivi et de reporting.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cafcdf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cafcdf8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8da1acb\" data-id=\"8da1acb\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4645da0 elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4645da0\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_24_319)\"><path d=\"M46.5666 0H42.2916C41.4998 0 40.8582 0.641625 40.8582 1.43344C40.8582 2.22506 41.4998 2.86669 42.2916 2.86669H45.1334V5.70853C45.1334 6.50025 45.7754 7.14188 46.5667 7.14188C47.3584 7.14188 48.0001 6.50025 48.0001 5.70844V1.43344C48.0001 0.641531 47.3584 0 46.5666 0ZM46.5666 25.8413C45.7754 25.8413 45.1334 26.4832 45.1334 27.2747V30.1164H42.2915C41.4998 30.1164 40.8582 30.7584 40.8582 31.5499C40.8582 32.3416 41.4998 32.9831 42.2916 32.9831H46.5666C47.3584 32.9831 48.0001 32.3416 48.0001 31.5498V27.2747C48.0001 26.4832 47.3584 25.8413 46.5666 25.8413ZM16.4503 7.14188C17.2416 7.14188 17.8836 6.50025 17.8836 5.70844V2.86678H20.7254C21.5168 2.86678 22.1588 2.22516 22.1588 1.43344C22.1588 0.641719 21.5167 0 20.7254 0H16.4504C15.6586 0 15.0169 0.641625 15.0169 1.43344V5.70844C15.0169 6.50025 15.6586 7.14188 16.4504 7.14188H16.4503ZM43.0701 24.0011L38.5617 17.0178L40.7004 9.05016C40.9871 7.98197 40.006 7.00894 38.944 7.29384L30.9767 9.43247L23.9924 4.92403C23.0637 4.32459 21.8324 4.96181 21.7831 6.06478L21.419 14.302L14.9165 19.5355C14.0512 20.234 14.2753 21.6075 15.3139 21.9961L19.102 23.4075L1.1199 41.3891C-0.370534 42.8797 -0.376065 45.297 1.1199 46.793L1.20015 46.8731C1.20118 46.8731 1.20118 46.8731 1.20118 46.8743C2.69059 48.3637 5.11347 48.3637 6.60503 46.8743L24.5867 28.8926L25.9981 32.6792C26.3878 33.7218 27.7624 33.9427 28.4576 33.078L33.6922 26.5741L41.9294 26.2101C43.0321 26.1628 43.6693 24.9313 43.0701 24.0011ZM4.57731 44.8465C4.20559 45.219 3.60062 45.219 3.22787 44.8465L3.14762 44.7664C3.0588 44.6778 2.98833 44.5726 2.94024 44.4567C2.89216 44.3409 2.86741 44.2167 2.86741 44.0912C2.86741 43.9658 2.89216 43.8416 2.94024 43.7257C2.98833 43.6099 3.0588 43.5047 3.14762 43.4161L22.0555 24.5083L23.0971 24.8962L23.4859 25.9387L4.57731 44.8465ZM32.9185 23.7394C32.7151 23.7484 32.5159 23.8006 32.3341 23.8925C32.1524 23.9844 31.9924 24.114 31.8646 24.2725L27.8051 29.3179C26.8559 26.7701 25.5547 23.2816 25.5547 23.2816C25.483 23.0891 25.3707 22.9143 25.2254 22.769C25.0802 22.6237 24.9054 22.5114 24.7128 22.4397C24.7128 22.4397 21.3938 21.2015 18.6766 20.1893L23.7222 16.1291C23.8807 16.0014 24.0102 15.8415 24.1021 15.6599C24.1941 15.4783 24.2463 15.2793 24.2554 15.0759L24.5371 8.68809L29.9569 12.1865C30.1252 12.295 30.3144 12.3671 30.5123 12.398C30.7102 12.4289 30.9124 12.418 31.1057 12.3659L37.2873 10.7074L35.6284 16.8887C35.5764 17.0821 35.5654 17.2842 35.5964 17.4821C35.6273 17.6799 35.6993 17.8691 35.8079 18.0374L39.3063 23.4574L32.9185 23.7394Z\" fill=\"#00C65B\"><\/path><\/g><defs><clipPath id=\"clip0_24_319\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-417b811 elementor-widget elementor-widget-heading\" data-id=\"417b811\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Flexible et \u00e9volutif<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d2e565 elementor-widget elementor-widget-text-editor\" data-id=\"2d2e565\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Adaptable \u00e0 tout volume d&rsquo;inspection et \u00e0 toutes les exigences de l&rsquo;entreprise.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-efc3ef0\" data-id=\"efc3ef0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-09c773a e-flex e-con-boxed e-con e-parent\" data-id=\"09c773a\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-99c59da elementor-widget elementor-widget-heading\" data-id=\"99c59da\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9volutionnez votre processus d'inspection<br>gr\u00e2ce \u00e0 Bexel !<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d069748 elementor-widget elementor-widget-text-editor\" data-id=\"d069748\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLe module d&rsquo;inspection par lots de Bexel garantit que vos inspections en vrac et vos certifications<br>sont trait\u00e9es de mani\u00e8re efficace, pr\u00e9cise et sans effort.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-3d9060e elementor-widget__width-auto elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3d9060e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/calcom.bexel.io\/team\/sales\/discovery\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9server une d\u00e9monstration<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Module de traitement par lots La gestion des inspections et certifications \u00e0 grande \u00e9chelle peut s&rsquo;av\u00e9rer fastidieuse, mais gr\u00e2ce au module d&rsquo;inspection par lots de Bexel, nous simplifions l&rsquo;ensemble du processus. Ce module est con\u00e7u pour rationaliser les importations d&rsquo;\u00e9quipements en vrac, automatiser la g\u00e9n\u00e9ration des certifications et am\u00e9liorer la pr\u00e9cision des donn\u00e9es, garantissant ainsi&#8230;<\/p>\n","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-991082","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/pages\/991082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/comments?post=991082"}],"version-history":[{"count":0,"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/pages\/991082\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.bexel.io\/fr\/wp-json\/wp\/v2\/media?parent=991082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}